{"id":782597,"date":"2026-09-02T14:10:08","date_gmt":"2026-09-02T08:40:08","guid":{"rendered":"https:\/\/anantrading.com\/blog\/product\/warmee-body-warmers-pack-of-7-pcs-safe-and-natural-8-hours-of-heat-air-activated-heat-packs-for-adults-and-children-travel-warmers-for-winters-trekking-camping\/"},"modified":"2026-09-02T14:10:09","modified_gmt":"2026-09-02T08:40:09","slug":"warmee-body-warmers-pack-of-7-pcs-safe-and-natural-8-hours-of-heat-air-activated-heat-packs-for-adults-and-children-travel-warmers-for-winters-trekking-camping","status":"publish","type":"product","link":"https:\/\/anantrading.com\/blog\/product\/warmee-body-warmers-pack-of-7-pcs-safe-and-natural-8-hours-of-heat-air-activated-heat-packs-for-adults-and-children-travel-warmers-for-winters-trekking-camping\/","title":{"rendered":"WARMEE Body Warmers (Pack of 7 pcs) Safe and Natural, 8+ Hours of Heat || Air Activated Heat Packs for Adults and Children || Travel Warmers for Winters, Trekking, Camping,"},"content":{"rendered":"<p><br \/>\nPrice: <span style=\"color:#b12704\">\u20b9875.00<\/span><br \/><i><small>(as of Sep 02, 2026 08:40:08 UTC &#8211; <span class=\"wp_automatic_amazon_disclaimer\" title=\"Product prices and availability are accurate as of the date\/time indicated and are subject to change. Any price and availability information displayed on [relevant Amazon Site(s), as applicable] at the time of purchase will apply to the purchase of this product.\">Details<\/span>)<\/small><\/i><\/p>\n<p><a href=\"https:\/\/www.amazon.in\/gp\/aws\/cart\/add.html?AssociateTag=anantrading59-21&#038;ASIN.1=B07KNB4H2K&#038;Quantity.1=1&#038;SubscriptionId=\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i0.wp.com\/valvepress.s3.amazonaws.com\/imgs\/buy_now.png?ssl=1&amp;w=75&amp;resize=75&amp;ssl=1 75w, https:\/\/i0.wp.com\/valvepress.s3.amazonaws.com\/imgs\/buy_now.png?ssl=1&amp;w=100&amp;resize=100&amp;ssl=1 100w, https:\/\/i0.wp.com\/valvepress.s3.amazonaws.com\/imgs\/buy_now.png?ssl=1&amp;w=150&amp;resize=150&amp;ssl=1 150w, https:\/\/i0.wp.com\/valvepress.s3.amazonaws.com\/imgs\/buy_now.png?ssl=1&amp;w=240&amp;resize=240&amp;ssl=1 240w, https:\/\/i0.wp.com\/valvepress.s3.amazonaws.com\/imgs\/buy_now.png?ssl=1&amp;w=320&amp;resize=320&amp;ssl=1 320w, https:\/\/i0.wp.com\/valvepress.s3.amazonaws.com\/imgs\/buy_now.png?ssl=1&amp;w=500&amp;resize=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/valvepress.s3.amazonaws.com\/imgs\/buy_now.png?ssl=1&amp;w=640&amp;resize=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/valvepress.s3.amazonaws.com\/imgs\/buy_now.png?ssl=1&amp;w=800&amp;resize=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/valvepress.s3.amazonaws.com\/imgs\/buy_now.png?ssl=1&amp;w=1024&amp;resize=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/valvepress.s3.amazonaws.com\/imgs\/buy_now.png?ssl=1&amp;w=1280&amp;resize=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/valvepress.s3.amazonaws.com\/imgs\/buy_now.png?ssl=1&amp;w=1600&amp;resize=1600&amp;ssl=1 1600w\" fifu-data-src=\"https:\/\/i0.wp.com\/valvepress.s3.amazonaws.com\/imgs\/buy_now.png?ssl=1\" class=\"lazyload\" data-src=\"image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\"><\/a><br \/>\n<\/p>\n<p>                                                 From the brand   <\/p>\n<p>                                              <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" alt=\"\" fifu-data-src=\"https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1\" class=\"a-lazy-loaded\" data-src=\"https:\/\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/0109c33e-e41f-4e9b-8011-954d196e9f1f.__CR0,0,4879,2083_PT0_SX1464_V1___.jpg\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/0109c33e-e41f-4e9b-8011-954d196e9f1f.__CR0,0,4879,2083_PT0_SX1464_V1___.jpg?ssl=1&amp;w=75&amp;resize=75&amp;ssl=1 75w, https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/0109c33e-e41f-4e9b-8011-954d196e9f1f.__CR0,0,4879,2083_PT0_SX1464_V1___.jpg?ssl=1&amp;w=100&amp;resize=100&amp;ssl=1 100w, https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/0109c33e-e41f-4e9b-8011-954d196e9f1f.__CR0,0,4879,2083_PT0_SX1464_V1___.jpg?ssl=1&amp;w=150&amp;resize=150&amp;ssl=1 150w, https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/0109c33e-e41f-4e9b-8011-954d196e9f1f.__CR0,0,4879,2083_PT0_SX1464_V1___.jpg?ssl=1&amp;w=240&amp;resize=240&amp;ssl=1 240w, https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/0109c33e-e41f-4e9b-8011-954d196e9f1f.__CR0,0,4879,2083_PT0_SX1464_V1___.jpg?ssl=1&amp;w=320&amp;resize=320&amp;ssl=1 320w, https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/0109c33e-e41f-4e9b-8011-954d196e9f1f.__CR0,0,4879,2083_PT0_SX1464_V1___.jpg?ssl=1&amp;w=500&amp;resize=500&amp;ssl=1 500w, https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/0109c33e-e41f-4e9b-8011-954d196e9f1f.__CR0,0,4879,2083_PT0_SX1464_V1___.jpg?ssl=1&amp;w=640&amp;resize=640&amp;ssl=1 640w, https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/0109c33e-e41f-4e9b-8011-954d196e9f1f.__CR0,0,4879,2083_PT0_SX1464_V1___.jpg?ssl=1&amp;w=800&amp;resize=800&amp;ssl=1 800w, https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/0109c33e-e41f-4e9b-8011-954d196e9f1f.__CR0,0,4879,2083_PT0_SX1464_V1___.jpg?ssl=1&amp;w=1024&amp;resize=1024&amp;ssl=1 1024w, https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/0109c33e-e41f-4e9b-8011-954d196e9f1f.__CR0,0,4879,2083_PT0_SX1464_V1___.jpg?ssl=1&amp;w=1280&amp;resize=1280&amp;ssl=1 1280w, https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/0109c33e-e41f-4e9b-8011-954d196e9f1f.__CR0,0,4879,2083_PT0_SX1464_V1___.jpg?ssl=1&amp;w=1600&amp;resize=1600&amp;ssl=1 1600w\" alt=\"\" fifu-data-src=\"https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/0109c33e-e41f-4e9b-8011-954d196e9f1f.__CR0,0,4879,2083_PT0_SX1464_V1___.jpg?ssl=1\" class=\"lazyload\" data-src=\"image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\">  <\/p>\n<h3> Warmee <\/h3>\n<p> Hand body foot warmer <\/p>\n<p>                                              <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" alt=\"more than 1500000 15 lakhs unit sold 1.5 million customers served\" fifu-data-src=\"https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1\" class=\"a-lazy-loaded\" data-src=\"https:\/\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/bc24970c-021f-479e-ad9b-0cb3086bef33.__CR0,0,1508,1887_PT0_SX362_V1___.jpg\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/bc24970c-021f-479e-ad9b-0cb3086bef33.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=75&amp;resize=75&amp;ssl=1 75w, https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/bc24970c-021f-479e-ad9b-0cb3086bef33.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=100&amp;resize=100&amp;ssl=1 100w, https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/bc24970c-021f-479e-ad9b-0cb3086bef33.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=150&amp;resize=150&amp;ssl=1 150w, https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/bc24970c-021f-479e-ad9b-0cb3086bef33.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=240&amp;resize=240&amp;ssl=1 240w, https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/bc24970c-021f-479e-ad9b-0cb3086bef33.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=320&amp;resize=320&amp;ssl=1 320w, https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/bc24970c-021f-479e-ad9b-0cb3086bef33.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=500&amp;resize=500&amp;ssl=1 500w, https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/bc24970c-021f-479e-ad9b-0cb3086bef33.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=640&amp;resize=640&amp;ssl=1 640w, https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/bc24970c-021f-479e-ad9b-0cb3086bef33.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=800&amp;resize=800&amp;ssl=1 800w, https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/bc24970c-021f-479e-ad9b-0cb3086bef33.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=1024&amp;resize=1024&amp;ssl=1 1024w, https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/bc24970c-021f-479e-ad9b-0cb3086bef33.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=1280&amp;resize=1280&amp;ssl=1 1280w, https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/bc24970c-021f-479e-ad9b-0cb3086bef33.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=1600&amp;resize=1600&amp;ssl=1 1600w\" alt=\"more than 1500000 15 lakhs unit sold 1.5 million customers served\" fifu-data-src=\"https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/bc24970c-021f-479e-ad9b-0cb3086bef33.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1\" class=\"lazyload\" data-src=\"image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\">  <\/p>\n<p>                                              <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" alt=\"why warmee hearts by itself natural ingredients safe for slights\" fifu-data-src=\"https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1\" class=\"a-lazy-loaded\" data-src=\"https:\/\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/df16d21b-0c24-4ddb-a5f5-ec835d1781fa.__CR0,0,1508,1887_PT0_SX362_V1___.jpg\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/df16d21b-0c24-4ddb-a5f5-ec835d1781fa.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=75&amp;resize=75&amp;ssl=1 75w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/df16d21b-0c24-4ddb-a5f5-ec835d1781fa.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=100&amp;resize=100&amp;ssl=1 100w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/df16d21b-0c24-4ddb-a5f5-ec835d1781fa.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=150&amp;resize=150&amp;ssl=1 150w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/df16d21b-0c24-4ddb-a5f5-ec835d1781fa.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=240&amp;resize=240&amp;ssl=1 240w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/df16d21b-0c24-4ddb-a5f5-ec835d1781fa.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=320&amp;resize=320&amp;ssl=1 320w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/df16d21b-0c24-4ddb-a5f5-ec835d1781fa.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=500&amp;resize=500&amp;ssl=1 500w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/df16d21b-0c24-4ddb-a5f5-ec835d1781fa.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=640&amp;resize=640&amp;ssl=1 640w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/df16d21b-0c24-4ddb-a5f5-ec835d1781fa.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=800&amp;resize=800&amp;ssl=1 800w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/df16d21b-0c24-4ddb-a5f5-ec835d1781fa.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=1024&amp;resize=1024&amp;ssl=1 1024w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/df16d21b-0c24-4ddb-a5f5-ec835d1781fa.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=1280&amp;resize=1280&amp;ssl=1 1280w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/df16d21b-0c24-4ddb-a5f5-ec835d1781fa.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=1600&amp;resize=1600&amp;ssl=1 1600w\" alt=\"why warmee hearts by itself natural ingredients safe for slights\" fifu-data-src=\"https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/df16d21b-0c24-4ddb-a5f5-ec835d1781fa.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1\" class=\"lazyload\" data-src=\"image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\">  <\/p>\n<h3> Our Best Sellers <\/h3>\n<p>                                              <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" alt=\"warmee for winters vacation for himalayas snow fall mountains sardi thandi baraf\" fifu-data-src=\"https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1\" class=\"a-lazy-loaded\" data-src=\"https:\/\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/07ded9c0-948c-40b2-a4db-dd715032ffda.__CR0,0,1508,1887_PT0_SX362_V1___.jpg\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/07ded9c0-948c-40b2-a4db-dd715032ffda.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=75&amp;resize=75&amp;ssl=1 75w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/07ded9c0-948c-40b2-a4db-dd715032ffda.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=100&amp;resize=100&amp;ssl=1 100w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/07ded9c0-948c-40b2-a4db-dd715032ffda.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=150&amp;resize=150&amp;ssl=1 150w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/07ded9c0-948c-40b2-a4db-dd715032ffda.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=240&amp;resize=240&amp;ssl=1 240w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/07ded9c0-948c-40b2-a4db-dd715032ffda.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=320&amp;resize=320&amp;ssl=1 320w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/07ded9c0-948c-40b2-a4db-dd715032ffda.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=500&amp;resize=500&amp;ssl=1 500w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/07ded9c0-948c-40b2-a4db-dd715032ffda.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=640&amp;resize=640&amp;ssl=1 640w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/07ded9c0-948c-40b2-a4db-dd715032ffda.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=800&amp;resize=800&amp;ssl=1 800w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/07ded9c0-948c-40b2-a4db-dd715032ffda.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=1024&amp;resize=1024&amp;ssl=1 1024w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/07ded9c0-948c-40b2-a4db-dd715032ffda.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=1280&amp;resize=1280&amp;ssl=1 1280w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/07ded9c0-948c-40b2-a4db-dd715032ffda.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=1600&amp;resize=1600&amp;ssl=1 1600w\" alt=\"warmee for winters vacation for himalayas snow fall mountains sardi thandi baraf\" fifu-data-src=\"https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/07ded9c0-948c-40b2-a4db-dd715032ffda.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1\" class=\"lazyload\" data-src=\"image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\">  <\/p>\n<p>                                              <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" alt=\"holidays winter break chirstmas new year chutti trip camping trekking\" fifu-data-src=\"https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1\" class=\"a-lazy-loaded\" data-src=\"https:\/\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/63f8c56c-837c-48ee-937c-92f14d2ecd04.__CR0,0,1508,1887_PT0_SX362_V1___.jpg\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/63f8c56c-837c-48ee-937c-92f14d2ecd04.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=75&amp;resize=75&amp;ssl=1 75w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/63f8c56c-837c-48ee-937c-92f14d2ecd04.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=100&amp;resize=100&amp;ssl=1 100w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/63f8c56c-837c-48ee-937c-92f14d2ecd04.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=150&amp;resize=150&amp;ssl=1 150w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/63f8c56c-837c-48ee-937c-92f14d2ecd04.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=240&amp;resize=240&amp;ssl=1 240w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/63f8c56c-837c-48ee-937c-92f14d2ecd04.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=320&amp;resize=320&amp;ssl=1 320w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/63f8c56c-837c-48ee-937c-92f14d2ecd04.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=500&amp;resize=500&amp;ssl=1 500w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/63f8c56c-837c-48ee-937c-92f14d2ecd04.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=640&amp;resize=640&amp;ssl=1 640w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/63f8c56c-837c-48ee-937c-92f14d2ecd04.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=800&amp;resize=800&amp;ssl=1 800w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/63f8c56c-837c-48ee-937c-92f14d2ecd04.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=1024&amp;resize=1024&amp;ssl=1 1024w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/63f8c56c-837c-48ee-937c-92f14d2ecd04.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=1280&amp;resize=1280&amp;ssl=1 1280w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/63f8c56c-837c-48ee-937c-92f14d2ecd04.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=1600&amp;resize=1600&amp;ssl=1 1600w\" alt=\"holidays winter break chirstmas new year chutti trip camping trekking\" fifu-data-src=\"https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/63f8c56c-837c-48ee-937c-92f14d2ecd04.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1\" class=\"lazyload\" data-src=\"image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\">  <\/p>\n<p>                                              <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" alt=\"warmee for men snowy mountains himachal kashmir\" fifu-data-src=\"https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1\" class=\"a-lazy-loaded\" data-src=\"https:\/\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/6b44bfd3-2960-43fe-8b87-027312f3ce75.__CR0,0,1508,1887_PT0_SX362_V1___.jpg\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/6b44bfd3-2960-43fe-8b87-027312f3ce75.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=75&amp;resize=75&amp;ssl=1 75w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/6b44bfd3-2960-43fe-8b87-027312f3ce75.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=100&amp;resize=100&amp;ssl=1 100w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/6b44bfd3-2960-43fe-8b87-027312f3ce75.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=150&amp;resize=150&amp;ssl=1 150w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/6b44bfd3-2960-43fe-8b87-027312f3ce75.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=240&amp;resize=240&amp;ssl=1 240w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/6b44bfd3-2960-43fe-8b87-027312f3ce75.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=320&amp;resize=320&amp;ssl=1 320w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/6b44bfd3-2960-43fe-8b87-027312f3ce75.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=500&amp;resize=500&amp;ssl=1 500w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/6b44bfd3-2960-43fe-8b87-027312f3ce75.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=640&amp;resize=640&amp;ssl=1 640w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/6b44bfd3-2960-43fe-8b87-027312f3ce75.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=800&amp;resize=800&amp;ssl=1 800w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/6b44bfd3-2960-43fe-8b87-027312f3ce75.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=1024&amp;resize=1024&amp;ssl=1 1024w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/6b44bfd3-2960-43fe-8b87-027312f3ce75.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=1280&amp;resize=1280&amp;ssl=1 1280w, https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/6b44bfd3-2960-43fe-8b87-027312f3ce75.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=1600&amp;resize=1600&amp;ssl=1 1600w\" alt=\"warmee for men snowy mountains himachal kashmir\" fifu-data-src=\"https:\/\/i3.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/6b44bfd3-2960-43fe-8b87-027312f3ce75.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1\" class=\"lazyload\" data-src=\"image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\">  <\/p>\n<p>                                              <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=75&resize=75&ssl=1 75w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=100&resize=100&ssl=1 100w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=150&resize=150&ssl=1 150w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=240&resize=240&ssl=1 240w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=320&resize=320&ssl=1 320w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=500&resize=500&ssl=1 500w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=640&resize=640&ssl=1 640w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=800&resize=800&ssl=1 800w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=1024&resize=1024&ssl=1 1024w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=1280&resize=1280&ssl=1 1280w, https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1&w=1600&resize=1600&ssl=1 1600w\" alt=\"warmee media presence forbes recoginition\" fifu-data-src=\"https:\/\/i3.wp.com\/images-na.ssl-images-amazon.com\/images\/G\/01\/x-locale\/common\/grey-pixel.gif?ssl=1\" class=\"a-lazy-loaded\" data-src=\"https:\/\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/e4f8de84-cc2f-4aef-96fe-529f40168105.__CR0,0,1508,1887_PT0_SX362_V1___.jpg\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" fifu-lazy=\"1\" fifu-data-sizes=\"auto\" fifu-data-srcset=\"https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/e4f8de84-cc2f-4aef-96fe-529f40168105.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=75&amp;resize=75&amp;ssl=1 75w, https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/e4f8de84-cc2f-4aef-96fe-529f40168105.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=100&amp;resize=100&amp;ssl=1 100w, https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/e4f8de84-cc2f-4aef-96fe-529f40168105.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=150&amp;resize=150&amp;ssl=1 150w, https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/e4f8de84-cc2f-4aef-96fe-529f40168105.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=240&amp;resize=240&amp;ssl=1 240w, https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/e4f8de84-cc2f-4aef-96fe-529f40168105.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=320&amp;resize=320&amp;ssl=1 320w, https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/e4f8de84-cc2f-4aef-96fe-529f40168105.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=500&amp;resize=500&amp;ssl=1 500w, https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/e4f8de84-cc2f-4aef-96fe-529f40168105.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=640&amp;resize=640&amp;ssl=1 640w, https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/e4f8de84-cc2f-4aef-96fe-529f40168105.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=800&amp;resize=800&amp;ssl=1 800w, https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/e4f8de84-cc2f-4aef-96fe-529f40168105.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=1024&amp;resize=1024&amp;ssl=1 1024w, https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/e4f8de84-cc2f-4aef-96fe-529f40168105.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=1280&amp;resize=1280&amp;ssl=1 1280w, https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/e4f8de84-cc2f-4aef-96fe-529f40168105.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1&amp;w=1600&amp;resize=1600&amp;ssl=1 1600w\" alt=\"warmee media presence forbes recoginition\" fifu-data-src=\"https:\/\/i2.wp.com\/m.media-amazon.com\/images\/S\/aplus-media-library-service-media\/e4f8de84-cc2f-4aef-96fe-529f40168105.__CR0,0,1508,1887_PT0_SX362_V1___.jpg?ssl=1\" class=\"lazyload\" data-src=\"image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/ywAAAAAAQABAAACAUwAOw==\">  <\/p>\n<p>Includes: Pack of 7 Body Warmers.<br \/>USE: Each pouch\/pack can be used One Time Only. Gets activated by air. Provides heat for more than 8 hours. This multipurpose body warmers can be used inside sweaters, jackets, sleeping bags windcheaters etc. Provides natural Heating which works even at extreme cold temperatures upto -30 degrees<br \/>Features: Can be used as Body warmer, Heat Pack, Heat pouch.<br \/>Travel Friendly: Easy to carry, odourless, long lasting. Ideal for trekkers, mountain climbers and other activities. Provides<br \/>Safe and Environment Friendly: Our Heat packs\/Heat pouches are ISO certified with Safe and Natural Ingredients used. Our body warmer does not cause any harm to the environment.<br \/>Warmee body warmers are ready to Use Air Activated Self Heating Warmers that do not need any Electricity or Hot Water.<br \/>\n<br \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p> From the brand Warmee Hand body foot warmer Our Best Sellers Includes: Pack of 7 Body Warmers.USE: Each pouch\/pack can be used One Time Only. Gets activated by air. Provides heat for more than 8 hours. This multipurpose body warmers can be used inside sweaters, jackets, sleeping bags windcheaters etc. [&hellip;]<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[44],"product_tag":[200],"class_list":["post-782597","product","type-product","status-publish","product_cat-bicycles-heavy-gym-equipment","product_tag-camping","desktop-align-left","tablet-align-left","mobile-align-left","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/anantrading.com\/blog\/wp-json\/wp\/v2\/product\/782597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anantrading.com\/blog\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/anantrading.com\/blog\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/anantrading.com\/blog\/wp-json\/wp\/v2\/comments?post=782597"}],"wp:attachment":[{"href":"https:\/\/anantrading.com\/blog\/wp-json\/wp\/v2\/media?parent=782597"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/anantrading.com\/blog\/wp-json\/wp\/v2\/product_brand?post=782597"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/anantrading.com\/blog\/wp-json\/wp\/v2\/product_cat?post=782597"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/anantrading.com\/blog\/wp-json\/wp\/v2\/product_tag?post=782597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}